<br />
<b>Notice</b>:  Function as_next_scheduled_action was called <strong>incorrectly</strong>. as_next_scheduled_action() was called before the Action Scheduler data store was initialized Please see <a href="https://developer.wordpress.org/advanced-administration/debug/debug-wordpress/">Debugging in WordPress</a> for more information. (This message was added in version 3.1.6.) in <b>/home/u809884960/domains/r2greensolutions.com/public_html/wp-includes/functions.php</b> on line <b>6114</b><br />
<br />
<b>Notice</b>:  Function as_next_scheduled_action was called <strong>incorrectly</strong>. as_next_scheduled_action() was called before the Action Scheduler data store was initialized Please see <a href="https://developer.wordpress.org/advanced-administration/debug/debug-wordpress/">Debugging in WordPress</a> for more information. (This message was added in version 3.1.6.) in <b>/home/u809884960/domains/r2greensolutions.com/public_html/wp-includes/functions.php</b> on line <b>6114</b><br />
{"id":580,"date":"2024-12-18T23:12:18","date_gmt":"2024-12-18T23:12:18","guid":{"rendered":"https:\/\/r2greensolutions.com\/?post_type=product&#038;p=580"},"modified":"2025-05-07T12:20:27","modified_gmt":"2025-05-07T12:20:27","slug":"houtvloerolie-naturel-750ml","status":"publish","type":"product","link":"https:\/\/r2greensolutions.com\/pt-b\/produto\/houtvloerolie-naturel-750ml\/","title":{"rendered":"\u00d3leo para assoalho de madeira natural 750ml"},"content":{"rendered":"<h2>\u00d3leo para madeira de jardim 0,75 litros<\/h2>\n<p>&nbsp;<\/p>\n<div>\n<p>Esse \u00f3leo contendo solvente \u00e9 adequado para azulejos de p\u00e1tio de madeira de cor natural. A madeira desgastada mostra que o ladrilho precisa de um novo tratamento com \u00f3leo. A manuten\u00e7\u00e3o regular garante que o ladrilho de madeira permane\u00e7a bonito por mais tempo.<\/p>\n<p><b>Esse \u00f3leo \u00e9 adequado para os seguintes azulejos de madeira para terra\u00e7o:<\/b><br \/>\nLadrilho de madeira para terra\u00e7o Stockholm 30x30x2,4cm<br \/>\nTelha de madeira para terra\u00e7o Malmo 30x30x2,4cm<\/p>\n<\/div>\n<div>Telha de madeira para terra\u00e7o Vasteras 30x30x2,4cm<\/div>\n<p>&nbsp;<\/p>\n<div class=\"h2\"><strong>Especifica\u00e7\u00f5es do produto<\/strong><\/div>\n<div><\/div>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td>\u00a0Tipo<\/td>\n<td>\u00a0\u00d3leo de manuten\u00e7\u00e3o para telhas de madeira para terra\u00e7os<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Fich\u00e1rio<\/td>\n<td>\u00a0\u00d3leo de linha\u00e7a<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Conte\u00fado<\/td>\n<td>\u00a00,75 litros<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Cor<\/td>\n<td>\u00a0Natural \/ incolor (Douglas)<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Consumo<\/td>\n<td>\u00a0Aprox. 10m2 por lata com 1 dem\u00e3o<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Densidade a 20\u00b0C<\/td>\n<td>\u00a00,85 g\/cm\u00b3<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Tempo de sa\u00edda em segundos no DIN 4 cup<\/td>\n<td>\u00a0&gt; 17 segundos a 20\u00b0C<\/td>\n<\/tr>\n<tr>\n<td>\u00a0N\u00edvel de brilho<\/td>\n<td>\u00a0Matt<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Certifica\u00e7\u00e3o<\/td>\n<td>\u00a0NEN-EN 71-3<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Recursos<\/td>\n<td>\u00a0- Repelente \u00e0 \u00e1gua<\/p>\n<div>\u00a0- Resistente \u00e0s intemp\u00e9ries e regulador de umidade<br \/>\n- Protege a madeira contra o ressecamento<br \/>\n- As variantes pigmentadas protegem contra o envelhecimento<br \/>\n- F\u00e1cil de processar<br \/>\n- P\u00f3s-tratamento sem lixamento<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Prepara\u00e7\u00e3o<\/td>\n<td>\u00a0- Para evitar atrasar a secagem, exponha a madeira ao clima por algum tempo antes do primeiro tratamento<\/p>\n<div>\u00a0- Remova a sujeira, a graxa e as algas com uma solu\u00e7\u00e3o de sab\u00e3o neutro. Em seguida, seque com um pano seco<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Processamento<\/td>\n<td>\u00a01. Mexa bem o \u00f3leo<\/p>\n<div>\u00a02. Aplique o \u00f3leo na dire\u00e7\u00e3o da fibra da madeira com um pincel plano ou pincel de bloco<br \/>\n3. Limpe o material n\u00e3o absorvido com uma escova ou pano seco ap\u00f3s, no m\u00e1ximo, 30 minutos<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Temperatura de processamento<\/td>\n<td>\u00a05 \u00b0C a 30 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Aplicativos<\/td>\n<td>\u00a0- Madeira em ambientes internos e externos<\/p>\n<div>\u00a0- M\u00f3veis (de jardim), terra\u00e7os e cercas de madeira<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\u00a0Dica<\/td>\n<td>\u00a0A madeira desgastada mostra que o azulejo precisa de um novo tratamento com \u00f3leo<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Caracter\u00edsticas do produto<\/strong><\/p>\n<ul>\n<li><strong>N\u00famero do item:<\/strong> 71009010<\/li>\n<li><strong>Cor:<\/strong> Marrom claro<\/li>\n<li><strong>Unidade de vendas:<\/strong> Cada<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Tuinhoutolie 0,75 liter &nbsp; Deze oplosmiddel-houdende olie is geschikt voor de houten terrastegels met naturel kleur. Verweerd hout laat zien dat de tegel toe is aan een nieuwe oliebehandeling. Regelmatig onderhoud zorgt dat de houten tegel langer mooi blijft. Deze olie is geschikt voor de volgende houten terrastegels: Houten terrastegel Stockholm 30x30x2,4cm Houten terrastegel Malmo [&hellip;]<\/p>","protected":false},"featured_media":581,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[27,19,26],"product_tag":[],"class_list":{"0":"post-580","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alle-producten","7":"product_cat-houten-tegels","8":"product_cat-overig","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/r2greensolutions.com\/pt-b\/wp-json\/wp\/v2\/product\/580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2greensolutions.com\/pt-b\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2greensolutions.com\/pt-b\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2greensolutions.com\/pt-b\/wp-json\/wp\/v2\/comments?post=580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2greensolutions.com\/pt-b\/wp-json\/wp\/v2\/media\/581"}],"wp:attachment":[{"href":"https:\/\/r2greensolutions.com\/pt-b\/wp-json\/wp\/v2\/media?parent=580"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2greensolutions.com\/pt-b\/wp-json\/wp\/v2\/product_brand?post=580"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2greensolutions.com\/pt-b\/wp-json\/wp\/v2\/product_cat?post=580"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2greensolutions.com\/pt-b\/wp-json\/wp\/v2\/product_tag?post=580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}